{"id":76542,"date":"2017-01-16T08:38:02","date_gmt":"2017-01-16T08:38:02","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/portal\/?p=76542"},"modified":"2017-01-17T03:20:17","modified_gmt":"2017-01-17T03:20:17","slug":"victima-sorprende-a-delincuente-dentro-de-su-casa-robando-herramientas","status":"publish","type":"post","link":"https:\/\/www.eltrabajo.cl\/2017\/victima-sorprende-a-delincuente-dentro-de-su-casa-robando-herramientas\/","title":{"rendered":"V\u00edctima sorprende a delincuente dentro de su casa robando herramientas"},"content":{"rendered":"<ul>\n<li><strong><span style=\"color: #ff0000;\">Fue capturado por Carabineros cuando hu\u00eda:<\/span>\u00a0El sujeto ingres\u00f3 a una vivienda de la Villa El Se\u00f1orial de San Felipe a pleno d\u00eda, siendo descubierto por el afectado. Tras ser formalizado en tribunales, el imputado qued\u00f3 en libertad con m\u00ednimas cautelares.<\/strong><\/li>\n<\/ul>\n<p>Un antisocial fue sorprendido en flagrancia por la propia v\u00edctima, robando especies a plena luz de d\u00eda, al interior de su vivienda ubicada en calle Julio Montero de la Villa El Se\u00f1orial de San Felipe, sustrayendo herramientas y siendo capturado minutos m\u00e1s tarde por Carabineros.<br \/>\nEl delito qued\u00f3 al descubierto, luego que un joven (la v\u00edctima) de 23 a\u00f1os de edad, observ\u00f3 que un desconocido se encontraba dentro de su casa, apoder\u00e1ndose de un taladro y un esmeril, siendo inmediatamente increpado por el afectado. Seg\u00fan su testimonio, el antisocial, al verse descubierto, desisti\u00f3 del robo, amenazando al propietario de agredirlo y que regresar\u00eda para vengarse.<br \/>\nMientras el delincuente huy\u00f3 del lugar, Carabineros recibi\u00f3 el llamado de auxilio del afectado, concurriendo una patrulla policial hasta el domicilio. Durante un recorrido por las arterias cercanas, el joven logr\u00f3 individualizar al delincuente que circulaba por la v\u00eda p\u00fablica, siendo capturado por los efectivos policiales a eso de las 17:15 horas.<br \/>\nEl detenido fue identificado como Fabi\u00e1n Enrique Cossio Campos de 31 a\u00f1os de edad, quien cuenta por antecedentes delictuales por delitos de robo en lugar no habitado y c\u00f3mplice de robo en bienes nacionales y de uso p\u00fablico, cometidos en San Felipe.<br \/>\nSu detenci\u00f3n fue controlada en el Juzgado de Garant\u00eda de San Felipe, para ser formalizado por la Fiscal\u00eda que investigar\u00e1 los hechos dentro de un plazo de 60 d\u00edas.<br \/>\nAl t\u00e9rmino de la audiencia el imputado recuper\u00f3 su libertad, quedando sujeto a las prohibiciones de salir del pa\u00eds y acercarse a la v\u00edctima.<br \/>\n<strong>Pablo Salinas Sald\u00edas<\/strong><\/p>\n<figure id=\"attachment_76543\" aria-describedby=\"caption-attachment-76543\" style=\"width: 530px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.eltrabajo.cl\/portal\/victima-sorprende-a-delincuente-dentro-de-su-casa-robando-herramientas\/fabian-cossio-campos\/\" rel=\"attachment wp-att-76543\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-76543\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/01\/fabian-cossio-campos.jpg?resize=530%2C350\" alt=\"El detenido Fabi\u00e1n Cossio Campos fue detenido tras ser identificado por la v\u00edctima, como autor de robo dentro de su propiedad en Villa El Se\u00f1orial de San Felipe.\" width=\"530\" height=\"350\" srcset=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/01\/fabian-cossio-campos.jpg?w=530&amp;ssl=1 530w, https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/01\/fabian-cossio-campos.jpg?resize=300%2C198&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/01\/fabian-cossio-campos.jpg?resize=150%2C99&amp;ssl=1 150w\" sizes=\"auto, (max-width: 530px) 100vw, 530px\" \/><\/a><figcaption id=\"caption-attachment-76543\" class=\"wp-caption-text\">El detenido Fabi\u00e1n Cossio Campos fue detenido tras ser identificado por la v\u00edctima, como autor de robo dentro de su propiedad en Villa El Se\u00f1orial de San Felipe.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Fue capturado por Carabineros cuando hu\u00eda:\u00a0El sujeto ingres\u00f3 a una vivienda de la Villa El Se\u00f1orial de San Felipe a pleno d\u00eda, siendo descubierto por <a class=\"mh-excerpt-more\" href=\"https:\/\/www.eltrabajo.cl\/2017\/victima-sorprende-a-delincuente-dentro-de-su-casa-robando-herramientas\/\" title=\"V\u00edctima sorprende a delincuente dentro de su casa robando herramientas\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":76543,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-76542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/01\/fabian-cossio-campos.jpg?fit=530%2C350&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/posts\/76542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/comments?post=76542"}],"version-history":[{"count":1,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/posts\/76542\/revisions"}],"predecessor-version":[{"id":76667,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/posts\/76542\/revisions\/76667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/media\/76543"}],"wp:attachment":[{"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/media?parent=76542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/categories?post=76542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/tags?post=76542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}