{"id":79789,"date":"2017-06-22T06:05:45","date_gmt":"2017-06-22T10:05:45","guid":{"rendered":"http:\/\/www.eltrabajo.cl\/2017\/?p=79789"},"modified":"2017-06-21T22:30:29","modified_gmt":"2017-06-22T02:30:29","slug":"pareja-es-detenida-por-microtrafico-de-pasta-base-en-villa-bernardo-cruz","status":"publish","type":"post","link":"https:\/\/www.eltrabajo.cl\/2017\/pareja-es-detenida-por-microtrafico-de-pasta-base-en-villa-bernardo-cruz\/","title":{"rendered":"Pareja es detenida por microtr\u00e1fico de pasta base en Villa Bernardo Cruz"},"content":{"rendered":"<figure id=\"attachment_79790\" aria-describedby=\"caption-attachment-79790\" style=\"width: 580px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-79790\" src=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/06\/PASTA-BASE-OS7.jpg?resize=580%2C348\" alt=\"Un total de 19 gramos de pasta base de coca\u00edna y $60.000 en efectivo fue el resultado del allanamiento gestionado por el OS7 de Carabineros al interior de una vivienda en la Villa Bernardo Cruz de San Felipe.\" width=\"580\" height=\"348\" srcset=\"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/06\/PASTA-BASE-OS7.jpg?w=580&amp;ssl=1 580w, https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/06\/PASTA-BASE-OS7.jpg?resize=300%2C180&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/06\/PASTA-BASE-OS7.jpg?resize=150%2C90&amp;ssl=1 150w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption id=\"caption-attachment-79790\" class=\"wp-caption-text\">Un total de 19 gramos de pasta base de coca\u00edna y $60.000 en efectivo fue el resultado del allanamiento gestionado por el OS7 de Carabineros al interior de una vivienda en la Villa Bernardo Cruz de San Felipe.<\/figcaption><\/figure>\n<ul>\n<li><strong><span style=\"color: #ff0000;\">Por segunda vez en menos de tres meses:<\/span>\u00a0Las diligencias policiales se concretaron la tarde de este martes por el OS7, logrando la detenci\u00f3n de un hombre y su pareja, quienes quedaron a disposici\u00f3n de la Fiscal\u00eda por el delito de microtr\u00e1fico de drogas.<\/strong><\/li>\n<\/ul>\n<p>Un total de 19 gramos de pasta base de coca\u00edna y $60.000 en dinero en efectivo, fue el resultado de un allanamiento ejecutado la tarde de este martes por personal del OS7 de Carabineros al interior de una vivienda ubicada en la Villa Bernardo Cruz de San Felipe, culminando con la detenci\u00f3n de una pareja que se dedicar\u00eda al microtr\u00e1fico de drogas.<br \/>\nLas diligencias policiales se gestionaron luego de diversas denuncias de vecinos que dar\u00edan cuenta de la venta de sustancias il\u00edcitas desde este domicilio, coordinando con el Ministerio P\u00fablico de San Felipe una orden judicial de entrada y registro de la propiedad, incaut\u00e1ndose 44 envoltorios de pasta base de coca\u00edna y dinero en efectivo atribuible a las ganancias obtenidas por las ventas del alucin\u00f3geno.<br \/>\nCarabineros inform\u00f3 que los imputados en menos de tres meses por segunda vez fueron detenidos por el mismo il\u00edcito. Los detenidos fueron individualizados con las iniciales M.A.D.O de 25 a\u00f1os de edad, quien manten\u00eda una orden de detenci\u00f3n pendiente por el delito de robo con violencia, y C.F.E.N. de 23 a\u00f1os de edad, con antecedentes, quedaron a disposici\u00f3n de la Fiscal\u00eda para la investigaci\u00f3n del caso.<br \/>\n<strong>Pablo Salinas Sald\u00edas<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Por segunda vez en menos de tres meses:\u00a0Las diligencias policiales se concretaron la tarde de este martes por el OS7, logrando la detenci\u00f3n de un <a class=\"mh-excerpt-more\" href=\"https:\/\/www.eltrabajo.cl\/2017\/pareja-es-detenida-por-microtrafico-de-pasta-base-en-villa-bernardo-cruz\/\" title=\"Pareja es detenida por microtr\u00e1fico de pasta base en Villa Bernardo Cruz\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":79790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-79789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.eltrabajo.cl\/2017\/wp-content\/uploads\/2017\/06\/PASTA-BASE-OS7.jpg?fit=580%2C348&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/posts\/79789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/comments?post=79789"}],"version-history":[{"count":1,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/posts\/79789\/revisions"}],"predecessor-version":[{"id":79791,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/posts\/79789\/revisions\/79791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/media\/79790"}],"wp:attachment":[{"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/media?parent=79789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/categories?post=79789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eltrabajo.cl\/2017\/wp-json\/wp\/v2\/tags?post=79789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}